{"id":5610,"date":"2020-12-07T14:51:46","date_gmt":"2020-12-07T19:51:46","guid":{"rendered":"https:\/\/jaquebec.com\/?p=5610"},"modified":"2022-11-09T11:11:02","modified_gmt":"2022-11-09T16:11:02","slug":"prix-reconnaissance-jeunesse-de-notre-benevole-yves-moreau","status":"publish","type":"post","link":"https:\/\/jaquebec.org\/fr\/2020\/12\/07\/prix-reconnaissance-jeunesse-de-notre-benevole-yves-moreau\/","title":{"rendered":"Prix reconnaissance jeunesse 2020 de notre b\u00e9n\u00e9vole Yves Moreau"},"content":{"rendered":"<p>[vc_row][vc_column][vc_column_text]<\/p>\n<div class=\"kvgmc6g5 cxmmr5t8 oygrvhab hcukyx3x c1et5uql ii04i59q\">\n<div dir=\"auto\">\n<p><strong>Un grand bravo \u00e0 Yves Moreau<\/strong>, b\u00e9n\u00e9vole Entreprise \u00c9tudiante, pour avoir remport\u00e9 le prix reconnaissance jeunesse 2020 dans la cat\u00e9gorie Intervenant axe Entrepreneuriat offert par le Secr\u00e9tariat \u00e0 la jeunesse du Qu\u00e9bec.<\/p>\n<\/div>\n<\/div>\n<p>[\/vc_column_text][\/vc_column][\/vc_row][vc_row][vc_column][vc_column_text css=&#8221;.vc_custom_1607371542457{margin-top: 25px !important;}&#8221;]<\/p>\n<div class=\"kvgmc6g5 cxmmr5t8 oygrvhab hcukyx3x c1et5uql ii04i59q\">\n<div dir=\"auto\">\n<p>Yves cultive l\u2019esprit entrepreneurial chez les jeunes, depuis maintenant 24 ans, par l\u2019entremise du programme <a href=\"https:\/\/jaquebec.org\/fr\/programmes\/programme-entreprise-etudiante\/\">Entreprise \u00e9tudiante<\/a> de JA Qu\u00e9bec. Il consacre son temps, son \u00e9nergie et son expertise \u00e0 faire fleurir l\u2019esprit entrepreneurial chez les jeunes. Son enseignement est pr\u00e9cieux \u00e0 plusieurs \u00e9gards, car aux comp\u00e9tences transmises s\u2019ajoutent la confiance en soi, l\u2019esprit d\u2019initiative et la volont\u00e9 de prendre en main son avenir. La pr\u00e9sence de Yves aupr\u00e8s des jeunes leur apporte une motivation suppl\u00e9mentaire \u00e0 poursuivre leur cheminement scolaire. Yves insuffle le go\u00fbt de r\u00e9ussir.<\/p>\n<\/div>\n<\/div>\n<p>[\/vc_column_text][\/vc_column][\/vc_row][vc_row][vc_column][vc_column_text css=&#8221;.vc_custom_1607371592305{margin-top: 25px !important;}&#8221;]<\/p>\n<div class=\"o9v6fnle cxmmr5t8 oygrvhab hcukyx3x c1et5uql ii04i59q\">\n<div dir=\"auto\">Nous vous proposons de d\u00e9couvrir Yves \u00e0 travers cette entrevue :<\/div>\n<\/div>\n<p>[\/vc_column_text][\/vc_column][\/vc_row][vc_row][vc_column][vc_raw_html css=&#8221;.vc_custom_1607371640721{margin-top: 25px !important;}&#8221;]JTNDaWZyYW1lJTIwc3JjJTNEJTIyaHR0cHMlM0ElMkYlMkZ3d3cueW91dHViZS5jb20lMkZlbWJlZCUyRmVjTnJWbHcweG40JTIyJTIwd2lkdGglM0QlMjI1NjAlMjIlMjBoZWlnaHQlM0QlMjIzMTUlMjIlMjBmcmFtZWJvcmRlciUzRCUyMjAlMjIlMjBhbGxvd2Z1bGxzY3JlZW4lM0QlMjJhbGxvd2Z1bGxzY3JlZW4lMjIlM0UlM0MlMkZpZnJhbWUlM0U=[\/vc_raw_html][\/vc_column][\/vc_row]<\/p>","protected":false},"excerpt":{"rendered":"<p>[vc_row][vc_column][vc_column_text] Un grand bravo \u00e0 Yves Moreau, b\u00e9n\u00e9vole Entreprise \u00c9tudiante, pour avoir remport\u00e9 le prix reconnaissance jeunesse 2020 dans la cat\u00e9gorie Intervenant axe Entrepreneuriat offert par le Secr\u00e9tariat \u00e0 la jeunesse du Qu\u00e9bec. [\/vc_column_text][\/vc_column][\/vc_row][vc_row][vc_column][vc_column_text css=&#8221;.vc_custom_1607371542457{margin-top: 25px !important;}&#8221;] Yves cultive l\u2019esprit entrepreneurial chez les jeunes, depuis maintenant 24 ans, par l\u2019entremise du programme Entreprise \u00e9tudiante de [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":5611,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_lmt_disableupdate":"","_lmt_disable":"","footnotes":""},"categories":[1],"tags":[],"class_list":["post-5610","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-non-classe"],"modified_by":null,"_links":{"self":[{"href":"https:\/\/jaquebec.org\/fr\/wp-json\/wp\/v2\/posts\/5610","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jaquebec.org\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/jaquebec.org\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/jaquebec.org\/fr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/jaquebec.org\/fr\/wp-json\/wp\/v2\/comments?post=5610"}],"version-history":[{"count":7,"href":"https:\/\/jaquebec.org\/fr\/wp-json\/wp\/v2\/posts\/5610\/revisions"}],"predecessor-version":[{"id":5619,"href":"https:\/\/jaquebec.org\/fr\/wp-json\/wp\/v2\/posts\/5610\/revisions\/5619"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/jaquebec.org\/fr\/wp-json\/wp\/v2\/media\/5611"}],"wp:attachment":[{"href":"https:\/\/jaquebec.org\/fr\/wp-json\/wp\/v2\/media?parent=5610"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/jaquebec.org\/fr\/wp-json\/wp\/v2\/categories?post=5610"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/jaquebec.org\/fr\/wp-json\/wp\/v2\/tags?post=5610"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}