{"id":9789,"date":"2023-07-04T14:10:39","date_gmt":"2023-07-04T18:10:39","guid":{"rendered":"https:\/\/jaquebec.org\/?p=9789"},"modified":"2023-07-04T14:12:13","modified_gmt":"2023-07-04T18:12:13","slug":"programme-jeunes-en-mouvement-vers-lemploi-avec-laiem","status":"publish","type":"post","link":"https:\/\/jaquebec.org\/fr\/2023\/07\/04\/programme-jeunes-en-mouvement-vers-lemploi-avec-laiem\/","title":{"rendered":"Programme \u00ab Jeunes en mouvement vers l\u2019emploi \u00bb avec l\u2019AIEM"},"content":{"rendered":"<p><\/p>\n<div class=\"wpb_text_column wpb_content_element  vc_custom_1687206909325\">\n<div class=\"wpb_wrapper\">\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Notre objectif est de contribuer \u00e0 briser les barri\u00e8res qui entravent certaines communaut\u00e9s, en particulier en termes d\u2019accessibilit\u00e9 \u00e0 la connaissance en entrepreneuriat, \u00e0 la pr\u00e9paration au march\u00e9 du travail et \u00e0 la sant\u00e9 financi\u00e8re. JA Qu\u00e9bec a r\u00e9ussi \u00e0 promouvoir cette cause en s\u2019associant \u00e0<\/span>\u00a0<b><a href=\"https:\/\/aiemont.com\/fr\/\" data-attribute-index=\"2\" data-entity-type=\"MINI_COMPANY\">Accueil aux Immigrants de l\u2019Est de Montr\u00e9al \u2013 AIEM<\/a><\/b><span style=\"color: #000000;\">, un organisme dont la mission est de soutenir et de favoriser l\u2019int\u00e9gration socio-\u00e9conomique des immigrants et des minorit\u00e9s visibles, afin qu\u2019ils deviennent des citoyens \u00e0 part enti\u00e8re de la soci\u00e9t\u00e9 d\u2019accueil. Nous participons cet \u00e9t\u00e9 au programme \u00ab\u00a0Jeunes en mouvement vers l\u2019emploi\u00a0\u00bb, financ\u00e9 par le gouvernement provincial pour faciliter l\u2019int\u00e9gration professionnelle des jeunes dans la r\u00e9gion de Montr\u00e9al. En r\u00e9sum\u00e9, il s\u2019agit d\u2019un excellent programme destin\u00e9 aux nouveaux arrivants \u00e2g\u00e9s de 15 \u00e0 30 ans, comprenant notamment 15 semaines de formation r\u00e9mun\u00e9r\u00e9es et 5 semaines de stage en entreprise r\u00e9mun\u00e9r\u00e9es. Dans le cadre de cette initiative, JA Qu\u00e9bec offrira chaque jeudi, au cours des mois de juin et de juillet, des conf\u00e9rences ainsi que des programmes \u00e9ducatifs \u00e0 la cohorte de l\u2019\u00e9t\u00e9 2023. J\u2019aimerais d\u2019ailleurs exprimer ma gratitude envers<\/span>\u00a0<a href=\"https:\/\/www.linkedin.com\/in\/ACoAAA3WC4wBBqnaJ-Eb1lbG6ckWRySAwNXz370\"><b>Allan Alva Lopez<\/b><\/a>\u00a0et\u00a0<a href=\"https:\/\/www.linkedin.com\/in\/ACoAABMF91IB2tG6bK0RTDwr5EWcttMqFzItLjg\"><b>Ana\u00efs Le-Juez<\/b><\/a><span style=\"color: #000000;\">, tous deux employ\u00e9s de la\u00a0<\/span><b><a href=\"https:\/\/www.bnc.ca\/\" data-attribute-index=\"10\" data-entity-type=\"MINI_COMPANY\">Banque Nationale du Canada<\/a><\/b>, <span style=\"color: #000000;\">pour avoir inaugur\u00e9 cet \u00e9v\u00e9nement cette semaine. Leur conf\u00e9rence, qui relate leur parcours acad\u00e9mique et professionnel avec un humanisme enviable, a \u00e9t\u00e9 grandement appr\u00e9ci\u00e9e par les jeunes ainsi que par l\u2019enseignante<\/span>\u00a0<a href=\"https:\/\/www.linkedin.com\/in\/ACoAACkCPHMBJ7PUaE96uw84ZZSz9sQQ2e9f0cQ\"><b>Sherelyng Vanessa Pe\u00f1a<\/b><\/a><span style=\"color: #000000;\">. Si vous souhaitez participer \u00e0 cette belle et importante initiative, je vous invite \u00e0 contacter d\u00e8s aujourd\u2019hui<\/span>\u00a0<strong><a href=\"mailto:dberard@jaquebec.org\">dberard@jaquebec.org<\/a><\/strong> <span style=\"color: #000000;\">pour r\u00e9server votre place. Cette exp\u00e9rience peut \u00e9galement \u00eatre v\u00e9cue en duo si vous souhaitez la partager avec un coll\u00e8gue !<\/span><\/p>\n<\/div>\n<\/div>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>Notre objectif est de contribuer \u00e0 briser les barri\u00e8res qui entravent certaines communaut\u00e9s, en particulier en termes d\u2019accessibilit\u00e9 \u00e0 la connaissance en entrepreneuriat, \u00e0 la pr\u00e9paration au march\u00e9 du travail et \u00e0 la sant\u00e9 financi\u00e8re. JA Qu\u00e9bec a r\u00e9ussi \u00e0 promouvoir cette cause en s\u2019associant \u00e0\u00a0Accueil aux Immigrants de l\u2019Est de Montr\u00e9al \u2013 AIEM, un [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":9790,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_lmt_disableupdate":"","_lmt_disable":"","footnotes":""},"categories":[1],"tags":[],"class_list":["post-9789","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-non-classe"],"modified_by":null,"_links":{"self":[{"href":"https:\/\/jaquebec.org\/fr\/wp-json\/wp\/v2\/posts\/9789","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jaquebec.org\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/jaquebec.org\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/jaquebec.org\/fr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/jaquebec.org\/fr\/wp-json\/wp\/v2\/comments?post=9789"}],"version-history":[{"count":4,"href":"https:\/\/jaquebec.org\/fr\/wp-json\/wp\/v2\/posts\/9789\/revisions"}],"predecessor-version":[{"id":9794,"href":"https:\/\/jaquebec.org\/fr\/wp-json\/wp\/v2\/posts\/9789\/revisions\/9794"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/jaquebec.org\/fr\/wp-json\/wp\/v2\/media\/9790"}],"wp:attachment":[{"href":"https:\/\/jaquebec.org\/fr\/wp-json\/wp\/v2\/media?parent=9789"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/jaquebec.org\/fr\/wp-json\/wp\/v2\/categories?post=9789"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/jaquebec.org\/fr\/wp-json\/wp\/v2\/tags?post=9789"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}